{"id":375,"date":"2022-01-14T05:51:19","date_gmt":"2022-01-13T21:51:19","guid":{"rendered":"https:\/\/www.inteks.com.sg\/?page_id=375"},"modified":"2025-11-28T15:36:52","modified_gmt":"2025-11-28T07:36:52","slug":"contact","status":"publish","type":"page","link":"https:\/\/www.inteks.com.sg\/es\/contact\/","title":{"rendered":"Contactos"},"content":{"rendered":"<div class=\"row\"  id=\"row-1342926613\">\n\n\t<div id=\"col-1755518871\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-1007045852\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1007045852 {\n  padding-top: 45px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2608534844\" class=\"text\">\n\t\t\n<p><strong>INTEK TECHNOLOGIES PTE LTD<\/strong> se fund\u00f3 en Singapur en 2019 como empresa de dise\u00f1o independiente (IDH) y fabricante de PCBA de productos inteligentes.<br \/>Hemos trabajado en el campo del dise\u00f1o de circuitos electr\u00f3nicos durante m\u00e1s de 10 a\u00f1os y tenemos una gran experiencia en el desarrollo, el dise\u00f1o y la producci\u00f3n. Si est\u00e1 buscando un proveedor profesional y eficiente, no dude en ponerse en contacto con nosotros en cualquier momento.<\/p>\n\t\t\n<style>\n#text-2608534844 {\n  font-size: 0.95rem;\n  line-height: 2.25;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row row-small\"  id=\"row-2048215704\">\n\n\t<div id=\"col-2066773026\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-1679798568\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1679798568 {\n  padding-top: 16px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3323743815\" class=\"text\">\n\t\t\n<h2>INFORMACI\u00d3N DE CONTACTO<\/h2>\n\t\t\n<style>\n#text-3323743815 {\n  font-size: 0.95rem;\n  line-height: 3;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"text-972944411\" class=\"text\">\n\t\t\n<h2>SINGAPORE OFFICE<\/h2>\n<p><strong>ADD :<\/strong> 11 Woodlands Close #10-20 Singapore 737853<br \/><strong>Tel :<\/strong> (+65) 9027 3095<br \/><strong>Correo electr\u00f3nico :<\/strong> intek@inteks.com.sg<\/p>\n<h2>SUCURSAL EN CHINA<\/h2>\n<h3>\u2014\u2014R&amp;D Center I<\/h3>\n<p><strong>ADD :<\/strong> 808, Building 8, Honghai BC, ZhongYa Silicon Valley,Songgang Street, Bao&#8217;an, Shenzhen, China<br \/><strong>Tel:<\/strong> (+65) 9026 9932<br \/><strong>Correo electr\u00f3nico:<\/strong> hongliang.gao@inteks.com.sg<\/p>\n<h3>\u2014\u2014R&amp;D Center II<\/h3>\n<p><strong>ADD :<\/strong> Habitaci\u00f3n 1616, Bloque A, Edificio 5, Fase III, Parque Industrial Huaqiang Creative, Calle Guanguang, Distrito Guangming, Shenzhen , China.<br \/><strong>Tel:<\/strong> (+86) 0755-2890 8776<br \/><strong>Correo electr\u00f3nico:<\/strong> project@szinteks.com<\/p>\n<h3>\u2014\u2014Factory<\/h3>\n<p><strong>ADD :<\/strong> 3-4\/F,Building B, No.80 Shilong Avenue, Shuitian CommunityShiyan Street, Bao&#8217;an District, Shenzhen,China.<\/p>\n<h3>Contacto con nosotros<\/h3>\n\t\t\n<style>\n#text-972944411 {\n  line-height: 2.25;\n}\n<\/style>\n\t<\/div>\n\t\n<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f140-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/375#wpcf7-f140-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/es\/wp-json\/wp\/v2\/pages\/375#wpcf7-f140-o1\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"140\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"855.3\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f140-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class='row row-large'>\n<div class=\"col large-6\">\n<p>*Nombre completo<\/p>\n<p><span class=\"wpcf7-form-control-wrap FirstName\"><input type=\"text\" name=\"FirstName\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span>\n<\/p><\/div>\n<div class=\"col large-6\">\n<p>*Pa\u00eds<\/p>\n<p><span class=\"wpcf7-form-control-wrap Country\"><input type=\"text\" name=\"Country\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span>\n<\/p><\/div>\n<div class=\"col large-6\">\n<p>* Correo electr\u00f3nico<\/p>\n<p><span class=\"wpcf7-form-control-wrap Email\"><input type=\"text\" name=\"Email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span>\n<\/p><\/div>\n<div class=\"col large-6\">\n<p>Tel\u00e9fono<\/p>\n<p><span class=\"wpcf7-form-control-wrap Phone\"><input type=\"tel\" name=\"Phone\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span>\n<\/p><\/div>\n<div class=\"col large-12\">\n<p>Mensaje<\/p>\n<p><span class=\"wpcf7-form-control-wrap Message\"><textarea name=\"Message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span>\n<\/p><\/div>\n<div class=\"col large-6\">\n<input type=\"submit\" value=\"Enviar\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/>\n<\/div>\n<\/div>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":[],"_links":{"self":[{"href":"https:\/\/www.inteks.com.sg\/es\/wp-json\/wp\/v2\/pages\/375"}],"collection":[{"href":"https:\/\/www.inteks.com.sg\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.inteks.com.sg\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.inteks.com.sg\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inteks.com.sg\/es\/wp-json\/wp\/v2\/comments?post=375"}],"version-history":[{"count":0,"href":"https:\/\/www.inteks.com.sg\/es\/wp-json\/wp\/v2\/pages\/375\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.inteks.com.sg\/es\/wp-json\/wp\/v2\/media?parent=375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}